{"id":278,"count":0,"description":"","link":"https:\/\/www.gesibras.com.br\/blog\/tag\/instalacao-de-rebite-de-rosca\/","name":"instala\u00e7\u00e3o de rebite de rosca","slug":"instalacao-de-rebite-de-rosca","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Arquivo de instala\u00e7\u00e3o de rebite de rosca - Blog Gesibr\u00e1s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gesibras.com.br\/blog\/tag\/instalacao-de-rebite-de-rosca\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivo de instala\u00e7\u00e3o de rebite de rosca - Blog Gesibr\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gesibras.com.br\/blog\/tag\/instalacao-de-rebite-de-rosca\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Gesibr\u00e1s\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.gesibras.com.br\/blog\/tag\/instalacao-de-rebite-de-rosca\/\",\"url\":\"https:\/\/www.gesibras.com.br\/blog\/tag\/instalacao-de-rebite-de-rosca\/\",\"name\":\"Arquivo de instala\u00e7\u00e3o de rebite de rosca - Blog Gesibr\u00e1s\",\"isPartOf\":{\"@id\":\"https:\/\/www.gesibras.com.br\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.gesibras.com.br\/blog\/tag\/instalacao-de-rebite-de-rosca\/#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.gesibras.com.br\/blog\/tag\/instalacao-de-rebite-de-rosca\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.gesibras.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"instala\u00e7\u00e3o de rebite de rosca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.gesibras.com.br\/blog\/#website\",\"url\":\"https:\/\/www.gesibras.com.br\/blog\/\",\"name\":\"Blog Gesibr\u00e1s\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.gesibras.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.gesibras.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.gesibras.com.br\/blog\/#organization\",\"name\":\"Blog Gesibr\u00e1s\",\"url\":\"https:\/\/www.gesibras.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.gesibras.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.gesibras.com.br\/blog\/wp-content\/uploads\/2024\/10\/logo2.webp\",\"contentUrl\":\"https:\/\/www.gesibras.com.br\/blog\/wp-content\/uploads\/2024\/10\/logo2.webp\",\"width\":920,\"height\":271,\"caption\":\"Blog Gesibr\u00e1s\"},\"image\":{\"@id\":\"https:\/\/www.gesibras.com.br\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivo de instala\u00e7\u00e3o de rebite de rosca - Blog Gesibr\u00e1s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gesibras.com.br\/blog\/tag\/instalacao-de-rebite-de-rosca\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquivo de instala\u00e7\u00e3o de rebite de rosca - Blog Gesibr\u00e1s","og_url":"https:\/\/www.gesibras.com.br\/blog\/tag\/instalacao-de-rebite-de-rosca\/","og_site_name":"Blog Gesibr\u00e1s","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.gesibras.com.br\/blog\/tag\/instalacao-de-rebite-de-rosca\/","url":"https:\/\/www.gesibras.com.br\/blog\/tag\/instalacao-de-rebite-de-rosca\/","name":"Arquivo de instala\u00e7\u00e3o de rebite de rosca - Blog Gesibr\u00e1s","isPartOf":{"@id":"https:\/\/www.gesibras.com.br\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.gesibras.com.br\/blog\/tag\/instalacao-de-rebite-de-rosca\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.gesibras.com.br\/blog\/tag\/instalacao-de-rebite-de-rosca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.gesibras.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"instala\u00e7\u00e3o de rebite de rosca"}]},{"@type":"WebSite","@id":"https:\/\/www.gesibras.com.br\/blog\/#website","url":"https:\/\/www.gesibras.com.br\/blog\/","name":"Blog Gesibr\u00e1s","description":"","publisher":{"@id":"https:\/\/www.gesibras.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gesibras.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.gesibras.com.br\/blog\/#organization","name":"Blog Gesibr\u00e1s","url":"https:\/\/www.gesibras.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.gesibras.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.gesibras.com.br\/blog\/wp-content\/uploads\/2024\/10\/logo2.webp","contentUrl":"https:\/\/www.gesibras.com.br\/blog\/wp-content\/uploads\/2024\/10\/logo2.webp","width":920,"height":271,"caption":"Blog Gesibr\u00e1s"},"image":{"@id":"https:\/\/www.gesibras.com.br\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.gesibras.com.br\/blog\/wp-json\/wp\/v2\/tags\/278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gesibras.com.br\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.gesibras.com.br\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.gesibras.com.br\/blog\/wp-json\/wp\/v2\/posts?tags=278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}